{"id":4567,"date":"2012-03-03T15:30:46","date_gmt":"2012-03-03T13:30:46","guid":{"rendered":"http:\/\/soaplexikon.de\/cms\/?p=4567"},"modified":"2014-04-15T20:31:45","modified_gmt":"2014-04-15T18:31:45","slug":"dallas-2012-jrs-timeline","status":"publish","type":"post","link":"https:\/\/soaplexikon.de\/cms\/dallas-2012-jrs-timeline\/","title":{"rendered":"Dallas (2012): JR&#8217;s Timeline"},"content":{"rendered":"<table border=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Dallas\" src=\"http:\/\/www.soaplexikon.de\/image\/dallas_2011_kl.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td>Mit der Umstellung der Facebookseiten auf die Timeline hat der US-Sender TNT die <a title=\"Dallas-Seite\" href=\"https:\/\/www.facebook.com\/DallasTNT\" target=\"_blank\">Dallas-Seite<\/a> zu J.R.s Sprachrohr gemacht.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--><\/p>\n<p>Die Timeline beginnt am 2. April 1978, mit dem Start der Serie Dallas, damals noch auf CBS. Sie beinhaltet Videos, Bilder und auch immer wieder J.R.s pers\u00f6nliche Meinung zu den Geschehnissen.<br \/>\nAber das Highlight d\u00fcrften die Jahre 1991 bis 2011 sein. In der Zeit, in der kein Dallas im Fernsehen zu sehen war, ist dennoch einiges geschehen, und JR zeigt auch aus diesen Phasen Bilder aus seinem Leben.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Bobby &amp; JR Ewing\" src=\"http:\/\/www.soaplexikon.de\/image\/dallas_2011.jpg\" alt=\"\" width=\"432\" height=\"287\" \/><\/p>\n<p style=\"text-align: center;\">\u00a9 TNT<\/p>\n<p>Aber nicht nur bei Facebook ist Dallas aktiv unterwegs: Auch bei <a title=\"Twitter\" href=\"https:\/\/twitter.com\/#!\/Dallas_TNT\" target=\"_blank\">Twitter<\/a> schafft es die Serie, die Follower bei Laune zu halten. Im sogenannten #DallasQuickie wird jede Folge der Erfolgsserie in 140 Zeichen zusammengefasst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit der Umstellung der Facebookseiten auf die Timeline hat der US-Sender TNT die Dallas-Seite zu J.R.s Sprachrohr gemacht.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[165],"tags":[],"class_list":["post-4567","post","type-post","status-publish","format-standard","hentry","category-dallas"],"_links":{"self":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/4567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/comments?post=4567"}],"version-history":[{"count":19,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/4567\/revisions"}],"predecessor-version":[{"id":33617,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/4567\/revisions\/33617"}],"wp:attachment":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/media?parent=4567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/categories?post=4567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/tags?post=4567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}