{"id":41649,"date":"2015-04-02T13:00:15","date_gmt":"2015-04-02T11:00:15","guid":{"rendered":"http:\/\/soaplexikon.de\/cms\/?p=41649"},"modified":"2019-07-06T09:45:23","modified_gmt":"2019-07-06T07:45:23","slug":"neighbours-backstage-mit-travis-burns","status":"publish","type":"post","link":"https:\/\/soaplexikon.de\/cms\/neighbours-backstage-mit-travis-burns\/","title":{"rendered":"Neighbours: Backstage mit Travis Burns"},"content":{"rendered":"<table border=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Neighbours\" src=\"http:\/\/www.soaplexikon.de\/image\/neighbours.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td>Newcomer Travis Burns alias &#8222;Tyler Brennan&#8220; nimmt die Zuschauer mit hinter die Kulissen der australischen Daily &#8222;<a title=\"Neighbours\" href=\"http:\/\/soaplexikon.de\/cms\/soaps-a-z\/neighbours\/\" target=\"_blank\" rel=\"noopener noreferrer\">Neighbours<\/a>&#8222;.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/raGSogz1e_w\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Newcomer Travis Burns alias &#8222;Tyler Brennan&#8220; nimmt die Zuschauer mit hinter die Kulissen der australischen Daily &#8222;Neighbours&#8222;.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1070,1071,1072,1073],"class_list":["post-41649","post","type-post","status-publish","format-standard","hentry","category-soaplexikon","tag-backstage","tag-behind-the-scenes","tag-hinter-den-kulissen","tag-making-of"],"_links":{"self":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/41649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/comments?post=41649"}],"version-history":[{"count":2,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/41649\/revisions"}],"predecessor-version":[{"id":44617,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/41649\/revisions\/44617"}],"wp:attachment":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/media?parent=41649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/categories?post=41649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/tags?post=41649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}