{"id":26955,"date":"2013-08-24T14:00:36","date_gmt":"2013-08-24T12:00:36","guid":{"rendered":"http:\/\/soaplexikon.de\/cms\/?p=26955"},"modified":"2014-04-21T11:45:48","modified_gmt":"2014-04-21T09:45:48","slug":"possession-1985","status":"publish","type":"post","link":"https:\/\/soaplexikon.de\/cms\/possession-1985\/","title":{"rendered":"Possession (1985)"},"content":{"rendered":"<table border=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Soaplexikon\" src=\"http:\/\/www.soaplexikon.de\/image\/sl-100.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td>Obwohl die letzten Produktionen absolute Flops gewesen waren, bestellte das Nine Network eine weitere Grundy Soap: &#8222;Possession&#8220;. Am 14. Januar 1985 ging die Saga \u00fcber reiche Bitches und verloren geglaubte Kinder auf Sendung.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--> Au\u00dferdem wurde eine Storyline \u00fcber Spione eingebaut. Diese Storylines waren zu dem Zeitpunkt in den USA der letzte Schrei, wo Luke und Lauras Flucht (General Hospital) vor Auftragskillern Jahre zuvor f\u00fcr enorme Einschaltquoten gesorgt hatte und nun s\u00e4mtliche US-Daytime Soaps auf den Zug aufgesprungen waren. Leider lie\u00df sich dies nicht auf die australische Soap \u00fcbertragen. Die Zuschauer hielten dies f\u00fcr Australien nicht sehr realistisch.<\/p>\n<p>Dann hatte die Soap auch noch das Problem, dass sie in manchen St\u00e4dten gegen die Soaps &#8222;Carson&#8217;s Law&#8220; und &#8222;<a title=\"Sons and Daughters\" href=\"http:\/\/soaplexikon.de\/cms\/sons-and-daughters\/\" target=\"_blank\">Sons and Daughters<\/a>&#8220; lief. Gerade letztere befand sich auf ihrem H\u00f6hepunkt, weswegen die Zuschauer der neuen Soap keine Chance gaben. Nach einem Sendeplatzwechsel und 52 ausgestrahlten Folgen wurde &#8222;Possession&#8220; eingestellt. In Deutschland lief die Soap komplett ab Dezember 1991 auf ProSieben unter dem Titel &#8222;Jane und Kathleen &#8211; Schicksalswege zweier Freundinnen&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obwohl die letzten Produktionen absolute Flops gewesen waren, bestellte das Nine Network eine weitere Grundy Soap: &#8222;Possession&#8220;. Am 14. Januar 1985 ging die Saga \u00fcber reiche Bitches und verloren geglaubte Kinder auf Sendung.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[237],"tags":[],"class_list":["post-26955","post","type-post","status-publish","format-standard","hentry","category-aussie-soaps"],"_links":{"self":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/26955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/comments?post=26955"}],"version-history":[{"count":5,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/26955\/revisions"}],"predecessor-version":[{"id":27680,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/26955\/revisions\/27680"}],"wp:attachment":[{"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/media?parent=26955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/categories?post=26955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/tags?post=26955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}