{"id":42373,"date":"2015-05-19T13:00:48","date_gmt":"2015-05-19T11:00:48","guid":{"rendered":"http:\/\/soaplexikon.de\/cms\/?p=42373"},"modified":"2015-05-19T19:49:27","modified_gmt":"2015-05-19T17:49:27","slug":"neighbours-vier-einsteiger","status":"publish","type":"post","link":"http:\/\/soaplexikon.de\/cms\/neighbours-vier-einsteiger\/","title":{"rendered":"Neighbours: Vier Einsteiger"},"content":{"rendered":"<table border=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Neighbours\" src=\"http:\/\/www.soaplexikon.de\/image\/neighbours.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td>Es gibt zahlreiche Neuzug\u00e4nge bei &#8222;<a title=\"Neighbours\" href=\"http:\/\/soaplexikon.de\/cms\/soaps-a-z\/neighbours\/\" target=\"_blank\">Neighbours<\/a>&#8222;.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more-->Matt Wilson spielt Aaron Brennan, den Bruder von Mark und Tyler. Zoe Cramond steigt als Paul Robinsons lang vermisste Tochter Amy ein. Sie bringt ihren 10-j\u00e4hrigen Sohn Jimmy mit, gespielt von Darcy Tadich. Dann kehrt noch Felix Mallard als Libbys Sohn Ben Kirk zur\u00fcck. Dieser zieht bei seinen Gro\u00dfeltern Karl und Susan ein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt zahlreiche Neuzug\u00e4nge bei &#8222;Neighbours&#8222;.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[482],"tags":[],"class_list":["post-42373","post","type-post","status-publish","format-standard","hentry","category-neighbours"],"_links":{"self":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/42373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/comments?post=42373"}],"version-history":[{"count":3,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/42373\/revisions"}],"predecessor-version":[{"id":42611,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/42373\/revisions\/42611"}],"wp:attachment":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/media?parent=42373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/categories?post=42373"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/tags?post=42373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}