{"id":34989,"date":"2014-06-09T18:00:33","date_gmt":"2014-06-09T16:00:33","guid":{"rendered":"http:\/\/soaplexikon.de\/cms\/?p=34989"},"modified":"2014-12-05T19:38:57","modified_gmt":"2014-12-05T18:38:57","slug":"telemundo-reina-de-corazones-07","status":"publish","type":"post","link":"http:\/\/soaplexikon.de\/cms\/telemundo-reina-de-corazones-07\/","title":{"rendered":"Telemundo: Reina de Corazones #07"},"content":{"rendered":"<table border=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"Telemundo\" src=\"http:\/\/www.soaplexikon.de\/image\/telemundo.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><\/td>\n<td>Nach ihrem schweren Unfall versucht Reina Ort\u00edz, sich an die gef\u00e4hrlichen Geheimnisse zu erinnern: &#8222;Reina de Corazones&#8220; (Queen of Hearts)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><!--more--><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"\/\/www.youtube.com\/embed\/NQqDhHyagiQ\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach ihrem schweren Unfall versucht Reina Ort\u00edz, sich an die gef\u00e4hrlichen Geheimnisse zu erinnern: &#8222;Reina de Corazones&#8220; (Queen of Hearts)<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[564],"tags":[],"class_list":["post-34989","post","type-post","status-publish","format-standard","hentry","category-telemundo-telenovelas"],"_links":{"self":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/34989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/comments?post=34989"}],"version-history":[{"count":2,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/34989\/revisions"}],"predecessor-version":[{"id":35000,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/posts\/34989\/revisions\/35000"}],"wp:attachment":[{"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/media?parent=34989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/categories?post=34989"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/soaplexikon.de\/cms\/wp-json\/wp\/v2\/tags?post=34989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}